{"id":644,"date":"2025-09-12T13:39:10","date_gmt":"2025-09-12T04:39:10","guid":{"rendered":"https:\/\/sumple.net\/hoanghuyen\/?page_id=644"},"modified":"2025-09-23T15:29:07","modified_gmt":"2025-09-23T06:29:07","slug":"%e5%a4%96%e6%a7%8b","status":"publish","type":"page","link":"https:\/\/sumple.net\/hoanghuyen\/%e5%a4%96%e6%a7%8b\/","title":{"rendered":"\u5916\u69cb"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"644\" class=\"elementor elementor-644\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f5cb23 e-flex e-con-boxed e-con e-parent\" data-id=\"8f5cb23\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19d2d18 elementor-widget elementor-widget-heading\" data-id=\"19d2d18\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u5916\u69cb\u5de5\u4e8b\u3000\uffe50000000\uff5e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68740d0 e-flex e-con-boxed e-con e-parent\" data-id=\"68740d0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2665be elementor-widget elementor-widget-image\" data-id=\"e2665be\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"2048\" height=\"820\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4369.jpeg\" class=\"attachment-full size-full wp-image-704\" alt=\"IMG_4369\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4369.jpeg 2048w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4369-300x120.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4369-1024x410.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4369-768x308.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4369-1536x615.jpeg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-286c909 e-grid e-con-boxed e-con e-parent\" data-id=\"286c909\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97511ef elementor-widget elementor-widget-image\" data-id=\"97511ef\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7158-1024x768.jpeg\" class=\"attachment-large size-large wp-image-733\" alt=\"IMG_7158\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7158-1024x768.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7158-300x225.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7158-768x576.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7158-1536x1152.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7158.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21353f6 elementor-widget elementor-widget-image\" data-id=\"21353f6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4821-1024x768.jpeg\" class=\"attachment-large size-large wp-image-737\" alt=\"IMG_4821\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4821-1024x768.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4821-300x225.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4821-768x576.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4821-1536x1152.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4821.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39c4b51 elementor-widget elementor-widget-image\" data-id=\"39c4b51\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4915-1024x768.jpeg\" class=\"attachment-large size-large wp-image-732\" alt=\"IMG_4915\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4915-1024x768.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4915-300x225.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4915-768x576.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4915-1536x1152.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4915.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bc0cae elementor-widget elementor-widget-image\" data-id=\"5bc0cae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4586-1024x768.jpeg\" class=\"attachment-large size-large wp-image-735\" alt=\"IMG_4586\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4586-1024x768.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4586-300x225.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4586-768x576.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4586-1536x1152.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4586.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd691be e-flex e-con-boxed e-con e-parent\" data-id=\"cd691be\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a252e29 elementor-widget elementor-widget-heading\" data-id=\"a252e29\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u30a6\u30c3\u30c9\u30c7\u30c3\u30ad\u3000\uffe5000000000\uff5e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c5f3d3 e-grid e-con-boxed e-con e-parent\" data-id=\"6c5f3d3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb78f34 elementor-widget elementor-widget-image\" data-id=\"fb78f34\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5668-1024x768.jpeg\" class=\"attachment-large size-large wp-image-727\" alt=\"IMG_5668\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5668-1024x768.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5668-300x225.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5668-768x576.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5668-1536x1152.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5668.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed0af0d elementor-widget elementor-widget-image\" data-id=\"ed0af0d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5913-1024x768.jpeg\" class=\"attachment-large size-large wp-image-728\" alt=\"IMG_5913\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5913-1024x768.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5913-300x225.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5913-768x576.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5913-1536x1152.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_5913.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d3c4fc e-flex e-con-boxed e-con e-parent\" data-id=\"3d3c4fc\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-30daa28 elementor-widget elementor-widget-image\" data-id=\"30daa28\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"454\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4521-1024x726.jpeg\" class=\"attachment-large size-large wp-image-705\" alt=\"IMG_4521\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4521-1024x726.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4521-300x213.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4521-768x544.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4521-1536x1088.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4521.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1bebfb8 e-flex e-con-boxed e-con e-parent\" data-id=\"1bebfb8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a5e1d3 elementor-widget elementor-widget-heading\" data-id=\"1a5e1d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u30ac\u30ec\u30fc\u30b8\u5de5\u4e8b\u3000\uffe50000000\uff5e<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0cec0c4 e-grid e-con-boxed e-con e-parent\" data-id=\"0cec0c4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d61cf8b elementor-widget elementor-widget-image\" data-id=\"d61cf8b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7072-1024x768.jpeg\" class=\"attachment-large size-large wp-image-742\" alt=\"IMG_7072\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7072-1024x768.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7072-300x225.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7072-768x576.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7072-1536x1152.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_7072.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7fdbb9 elementor-widget elementor-widget-image\" data-id=\"c7fdbb9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4980-1024x768.jpeg\" class=\"attachment-large size-large wp-image-741\" alt=\"IMG_4980\" srcset=\"https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4980-1024x768.jpeg 1024w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4980-300x225.jpeg 300w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4980-768x576.jpeg 768w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4980-1536x1152.jpeg 1536w, https:\/\/sumple.net\/hoanghuyen\/wp-content\/uploads\/2025\/09\/IMG_4980.jpeg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" loading=\"lazy\" decoding=\"async\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u5916\u69cb\u5de5\u4e8b\u3000\uffe50000000\uff5e \u30a6\u30c3\u30c9<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-644","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sumple.net\/hoanghuyen\/wp-json\/wp\/v2\/pages\/644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sumple.net\/hoanghuyen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sumple.net\/hoanghuyen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sumple.net\/hoanghuyen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sumple.net\/hoanghuyen\/wp-json\/wp\/v2\/comments?post=644"}],"version-history":[{"count":13,"href":"https:\/\/sumple.net\/hoanghuyen\/wp-json\/wp\/v2\/pages\/644\/revisions"}],"predecessor-version":[{"id":745,"href":"https:\/\/sumple.net\/hoanghuyen\/wp-json\/wp\/v2\/pages\/644\/revisions\/745"}],"wp:attachment":[{"href":"https:\/\/sumple.net\/hoanghuyen\/wp-json\/wp\/v2\/media?parent=644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}